{"id":5949,"count":1,"description":"","link":"https:\/\/football-tribe.com\/vietnam\/tag\/loi-nguoc-dong\/","name":"l\u1ed9i ng\u01b0\u1ee3c d\u00f2ng","slug":"loi-nguoc-dong","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/tags\/5949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/posts?tags=5949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}