{"id":5070,"count":1,"description":"","link":"https:\/\/football-tribe.com\/vietnam\/tag\/chu-nha\/","name":"ch\u1ee7 nh\u00e0","slug":"chu-nha","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/tags\/5070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/football-tribe.com\/vietnam\/wp-json\/wp\/v2\/posts?tags=5070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}