{"id":36535,"date":"2019-11-08T14:23:51","date_gmt":"2019-11-08T07:23:51","guid":{"rendered":"https:\/\/football-tribe.com\/thailand\/?p=36535"},"modified":"2019-11-08T14:23:51","modified_gmt":"2019-11-08T07:23:51","slug":"%e0%b9%80%e0%b8%9a%e0%b8%99%e0%b9%80%e0%b8%8b%e0%b8%a1%e0%b9%88%e0%b8%b2-%e0%b8%8a%e0%b8%9b%e0%b8%a5-15%e0%b8%9b%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/football-tribe.com\/thailand\/2019\/11\/08\/%e0%b9%80%e0%b8%9a%e0%b8%99%e0%b9%80%e0%b8%8b%e0%b8%a1%e0%b9%88%e0%b8%b2-%e0%b8%8a%e0%b8%9b%e0%b8%a5-15%e0%b8%9b%e0%b8%b5\/","title":{"rendered":"\u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e0b\u0e31\u0e25\u0e42\u0e27\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e02\u0e2d\u0e07 \u0e25\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e25 \u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e48 (\u0e21\u0e35\u0e04\u0e25\u0e34\u0e1b)"},"content":{"rendered":"<h2><strong>\u0e04\u0e32\u0e23\u0e34\u0e21 \u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e23\u0e2d\u0e31\u0e25 \u0e21\u0e32\u0e14\u0e23\u0e34\u0e14 \u0e17\u0e33\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e22\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e19\u0e28\u0e36\u0e01 \u0e22\u0e39\u0e1f\u0e48\u0e32 \u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 <\/strong><strong>15 <\/strong><strong>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19 <\/strong><strong>\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32 \u0e25\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e25 \u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e48 \u0e08\u0e2d\u0e21\u0e17\u0e31\u0e1e\u0e15\u0e31\u0e27\u0e40\u0e01\u0e48\u0e07 \u0e1a\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e42\u0e25\u0e19\u0e48\u0e32<\/strong><\/h2>\n<p>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e38\u0e14\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04\u0e40\u0e2b\u0e21\u0e32\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 2 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48 &#8220;<a href=\"https:\/\/football-tribe.com\/thailand\/tag\/%e0%b9%80%e0%b8%a3%e0%b8%ad%e0%b8%b1%e0%b8%a5-%e0%b8%a1%e0%b8%b2%e0%b8%94%e0%b8%a3%e0%b8%b4%e0%b8%94\/\">\u0e23\u0e32\u0e0a\u0e31\u0e19\u0e0a\u0e38\u0e14\u0e02\u0e32\u0e27<\/a>&#8221; \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e01\u0e32\u0e25\u0e32\u0e15\u0e32\u0e0b\u0e32\u0e23\u0e32\u0e22 \u0e17\u0e35\u0e21\u0e14\u0e31\u0e07\u0e08\u0e32\u0e01 \u0e15\u0e38\u0e23\u0e01\u0e35 6-0 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30 <a href=\"https:\/\/football-tribe.com\/thailand\/tag\/%e0%b8%a5%e0%b8%b4%e0%b9%82%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%a5-%e0%b9%80%e0%b8%a1%e0%b8%aa%e0%b8%8b%e0%b8%b5%e0%b9%88\/\">\u0e25\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e25 \u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e48<\/a> \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e40\u0e1e\u0e35\u0e22\u0e07 2 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e19\u0e35\u0e49<\/p>\n<p>\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e19\u0e40\u0e01\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e39\u0e01\u0e17\u0e35\u0e48 49 \u0e41\u0e25\u0e30 50 \u0e02\u0e2d\u0e07 \u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35 \u0e22\u0e39\u0e1f\u0e48\u0e32 \u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c\u0e25\u0e35\u0e01 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30 \u0e40\u0e23\u0e2d\u0e31\u0e25 \u0e21\u0e32\u0e14\u0e23\u0e34\u0e14 \u0e19\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e22\u0e49\u0e32\u0e22\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e35\u0e21\u0e08\u0e32\u0e01 \u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01 \u0e25\u0e35\u0e22\u0e07 \u0e43\u0e19\u0e1b\u0e35 2009 \u0e42\u0e14\u0e22 \u0e13 \u0e02\u0e13\u0e30\u0e19\u0e35\u0e49 \u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e23\u0e31\u0e49\u0e07\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 4 \u0e1c\u0e39\u0e49\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e28\u0e36\u0e01 \u0e22\u0e39\u0e1f\u0e48\u0e32 \u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c\u0e25\u0e35\u0e01 (62 \u0e25\u0e39\u0e01 \u0e01\u0e31\u0e1a \u0e40\u0e23\u0e2d\u0e31\u0e25 \u0e21\u0e32\u0e14\u0e23\u0e34\u0e14 \u0e41\u0e25\u0e30 \u0e25\u0e35\u0e22\u0e07) \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07 <a href=\"https:\/\/football-tribe.com\/thailand\/tag\/%e0%b8%84%e0%b8%a3%e0%b8%b4%e0%b8%aa%e0%b9%80%e0%b8%95%e0%b8%b5%e0%b8%a2%e0%b9%82%e0%b8%99-%e0%b9%82%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%a5%e0%b9%82%e0%b8%94\/\">\u0e04\u0e23\u0e34\u0e2a\u0e40\u0e15\u0e35\u0e22\u0e42\u0e19\u0e48 \u0e42\u0e23\u0e19\u0e31\u0e25\u0e42\u0e14\u0e49<\/a> (127),\u00a0 \u0e25\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e25 \u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e48 (113) \u0e41\u0e25\u0e30 \u0e23\u0e32\u0e2d\u0e39\u0e25 \u0e01\u0e2d\u0e19\u0e0b\u0e32\u0e40\u0e25\u0e0b (71)<\/p>\n<p>&#8220;\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e19\u0e32\u0e1a\u0e34\u0e27&#8221; \u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e42\u0e21\u0e2a\u0e23 &#8220;\u0e40\u0e23\u0e32\u0e22\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e48\u0e19\u0e14\u0e35 \u0e41\u0e16\u0e21\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2d\u0e35\u0e01 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19\u0e1a\u0e2d\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e1c\u0e21\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e15\u0e33\u0e19\u0e32\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e15\u0e2d\u0e19\u0e1c\u0e21\u0e40\u0e0b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e31\u0e1a\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e1c\u0e21\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e32\u0e22\u0e37\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e08\u0e38\u0e14\u0e19\u0e35\u0e49 \u0e1c\u0e21\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e08\u0e23\u0e34\u0e07\u0e46&#8221;<\/p>\n<div class=\"dugout-video dugout-embed-eyJrZXkiOiJzb0QyQ1ZGNCIsInAiOiJmb290YmFsbHRyaWJlIiwicGwiOiIifQ==\"><\/div>\n<p><script type=\"text\/javascript\" src=\"https:\/\/embed.dugout.com\/v3.1\/footballtribe.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e32\u0e23\u0e34\u0e21 \u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e23\u0e2d\u0e31\u0e25 \u0e21\u0e32\u0e14\u0e23\u0e34\u0e14 \u0e17\u0e33\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e22\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e19\u0e28\u0e36\u0e01 \u0e22\u0e39\u0e1f\u0e48\u0e32 \u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 15 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19 \u0e40\u0e17\u0e35\u0e22 &hellip; <a href=\"https:\/\/football-tribe.com\/thailand\/2019\/11\/08\/%e0%b9%80%e0%b8%9a%e0%b8%99%e0%b9%80%e0%b8%8b%e0%b8%a1%e0%b9%88%e0%b8%b2-%e0%b8%8a%e0%b8%9b%e0%b8%a5-15%e0%b8%9b%e0%b8%b5\/\" class=\"tribe-more-link\">Continue reading &#8220;\u0e40\u0e1a\u0e19\u0e40\u0e0b\u0e21\u0e48\u0e32 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e0b\u0e31\u0e25\u0e42\u0e27\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e02\u0e2d\u0e07 \u0e25\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e25 \u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e48 (\u0e21\u0e35\u0e04\u0e25\u0e34\u0e1b)&#8221;<\/a><\/p>\n","protected":false},"author":11,"featured_media":36536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2080,600],"tags":[509,2202,2226,451,537],"class_list":["post-36535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2080","category-la-liga","tag-509","tag-2202","tag-2226","tag-451","tag-537"],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/36535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/comments?post=36535"}],"version-history":[{"count":3,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/36535\/revisions"}],"predecessor-version":[{"id":36539,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/36535\/revisions\/36539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media\/36536"}],"wp:attachment":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media?parent=36535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/categories?post=36535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/tags?post=36535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}