{"id":30060,"date":"2018-06-23T21:40:00","date_gmt":"2018-06-23T14:40:00","guid":{"rendered":"https:\/\/football-tribe.com\/thailand\/?p=30060"},"modified":"2018-06-23T21:40:00","modified_gmt":"2018-06-23T14:40:00","slug":"chan-comeback-cambodia","status":"publish","type":"post","link":"https:\/\/football-tribe.com\/thailand\/2018\/06\/23\/chan-comeback-cambodia\/","title":{"rendered":"\u0e15\u0e32\u0e22\u0e23\u0e31\u0e07!\u0e08\u0e31\u0e19 \u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e1b\u0e31\u0e14\u0e04\u0e49\u0e32\u0e41\u0e02\u0e49\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e2b\u0e27\u0e19\u0e0b\u0e1a\u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15"},"content":{"rendered":"<p>\u0e08\u0e31\u0e19 \u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32 \u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e04\u0e49\u0e32\u0e41\u0e02\u0e49\u0e07\u0e01\u0e31\u0e1a \u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e2d\u0e14\u0e35\u0e15\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e41\u0e22\u0e01\u0e17\u0e32\u0e07\u0e01\u0e31\u0e1a \u0e1b\u0e30\u0e2b\u0e31\u0e07 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e43\u0e19\u0e25\u0e35\u0e01\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22<\/p>\n<p>\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e32 &#8220;\u0e40\u0e21\u0e2a\u0e0b\u0e35\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32&#8221; \u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e02\u0e49\u0e07\u0e40\u0e083\u0e25\u0e35\u0e01 \u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e01\u0e31\u0e1a \u0e1f\u0e39\u0e08\u0e34\u0e40\u0e2d\u0e14\u0e30 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e1b\u0e30\u0e2b\u0e31\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e14\u0e49\u0e25\u0e07\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e1e\u0e35\u0e22\u0e07 10 \u0e19\u0e31\u0e14\u0e01\u0e48\u0e2d\u0e19\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e02\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e15\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e08\u0e49\u0e32\u0e15\u0e31\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19\u0e19\u0e35\u0e49\u0e27\u0e48\u0e32<\/p>\n<p>&#8220;\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e21\u0e1c\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e25\u0e35\u0e01\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49&#8221;<\/p>\n<p>&#8220;\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e41\u0e25\u0e30\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e25\u0e35\u0e01\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e0b\u0e36\u0e48\u0e48\u0e07\u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e22\u0e31\u0e07\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49&#8221;<\/p>\n<p>&#8220;\u0e1c\u0e21\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e40\u0e40\u0e14\u0e19 \u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15\u0e44\u0e14\u0e49\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e1a \u0e1b\u0e32\u0e2b\u0e31\u0e07 \u0e1c\u0e21\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e25\u0e22 \u0e42\u0e04\u0e49\u0e0a\u0e0a\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e1c\u0e21\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15 \u0e1c\u0e21\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e40\u0e01\u0e21\u0e23\u0e38\u0e01\u0e1e\u0e2d\u0e14\u0e35&#8221;<\/p>\n<p>&#8220;\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e2b\u0e23\u0e2d\u0e01\u0e19\u0e30\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e32\u0e1b\u0e32\u0e2b\u0e31\u0e07\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e15\u0e31\u0e27\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27&#8221; \u0e08\u0e31\u0e19 \u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e08\u0e31\u0e19 \u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32 \u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e04\u0e49\u0e32\u0e41\u0e02\u0e49\u0e07\u0e01\u0e31\u0e1a \u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e2d\u0e14\u0e35\u0e15\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31 &hellip; <a href=\"https:\/\/football-tribe.com\/thailand\/2018\/06\/23\/chan-comeback-cambodia\/\" class=\"tribe-more-link\">Continue reading &#8220;\u0e15\u0e32\u0e22\u0e23\u0e31\u0e07!\u0e08\u0e31\u0e19 \u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e1b\u0e31\u0e14\u0e04\u0e49\u0e32\u0e41\u0e02\u0e49\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e2b\u0e27\u0e19\u0e0b\u0e1a\u0e40\u0e1a\u0e34\u0e07\u0e40\u0e01\u0e15&#8221;<\/a><\/p>\n","protected":false},"author":11,"featured_media":17681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[154],"class_list":["post-30060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football-asean","tag-154"],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/30060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/comments?post=30060"}],"version-history":[{"count":0,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/30060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media\/17681"}],"wp:attachment":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media?parent=30060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/categories?post=30060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/tags?post=30060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}