{"id":23404,"date":"2018-03-28T13:09:53","date_gmt":"2018-03-28T06:09:53","guid":{"rendered":"https:\/\/football-tribe.com\/thailand\/?p=23404"},"modified":"2018-03-28T13:09:53","modified_gmt":"2018-03-28T06:09:53","slug":"rajevac-thailand-team","status":"publish","type":"post","link":"https:\/\/football-tribe.com\/thailand\/2018\/03\/28\/rajevac-thailand-team\/","title":{"rendered":"\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19!\u0e23\u0e32\u0e40\u0e22\u0e27\u0e31\u0e0a\u0e0a\u0e35\u0e49\u0e0a\u0e31\u0e14\u0e0a\u0e49\u0e32\u0e07\u0e28\u0e36\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e15\u0e48\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a"},"content":{"rendered":"<div class=\"_5x46 _1yz1 clearfix\">\n<div class=\"clearfix _5va3\">\n<div class=\"clearfix _42ef\">\n<div class=\"_5va4\">\n<div class=\"_6a _5u5j\">\n<div class=\"_6a _5u5j _6b\">\n<div id=\"feed_subtitle_650244365306498:6:0\" class=\"_5pcp _5lel _2jyu _232_\">\u0e21\u0e34\u0e42\u0e25\u0e27\u0e32\u0e19 \u0e23\u0e32\u0e40\u0e22\u0e27\u0e31\u0e0a \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e39\u0e49\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e0a\u0e49\u0e32\u0e07\u0e28\u0e36\u0e01\u0e43\u0e19\u0e22\u0e38\u0e04\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e41\u0e15\u0e48\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e17\u0e35\u0e21\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"js_3q6\" class=\"_5pbx userContent _3576\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\">\n<div id=\"id_5abb3115d294b2928967983\" class=\"text_exposed_root text_exposed\">\n<p>\u0e2d\u0e14\u0e35\u0e15\u0e01\u0e38\u0e19\u0e0b\u0e37\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e19\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e02\u0e49\u0e32\u0e23\u0e2d\u0e1a 8 \u0e17\u0e35\u0e21\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e04\u0e38\u0e21 \u0e0a\u0e49\u0e32\u0e07\u0e28\u0e36\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e16\u0e39\u0e01\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e22\u0e38\u0e04\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e17\u0e23\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e0a\u0e32\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e35\u0e22\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e1e\u0e32\u0e17\u0e35\u0e21\u0e04\u0e27\u0e49\u0e32\u0e23\u0e2d\u0e07\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e04\u0e34\u0e07\u0e2a\u0e4c\u0e04\u0e31\u0e1e 2018 \u0e15\u0e2d\u0e1a\u0e16\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e27\u0e48\u0e32<\/p>\n<div class=\"text_exposed_show\">\n<p><strong>&#8220;\u0e08\u0e23\u0e34\u0e07\u0e46\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e23\u0e38\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e1a\u0e38\u0e01\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2a\u0e35\u0e22 4 \u0e2b\u0e23\u0e37\u0e2d 5 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e19\u0e40\u0e01\u0e21 \u0e21\u0e31\u0e19\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e19\u0e49\u0e19\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c&#8221;<\/strong><\/p>\n<p><strong>&#8220;\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e21\u0e2d\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e21\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e48\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e21\u0e23\u0e38\u0e01\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07&#8221;<\/strong><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e42\u0e25\u0e27\u0e32\u0e19 \u0e23\u0e32\u0e40\u0e22\u0e27\u0e31\u0e0a \u0e40\u0e1e\u0e34\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e04\u0e38\u0e21\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e2d\u0e35\u0e01 2 \u0e1b\u0e35<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e34\u0e42\u0e25\u0e27\u0e32\u0e19 \u0e23\u0e32\u0e40\u0e22\u0e27\u0e31\u0e0a \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e39\u0e49\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e0a\u0e49\u0e32\u0e07\u0e28\u0e36\u0e01\u0e43\u0e19\u0e22\u0e38\u0e04\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e41\u0e15\u0e48\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e17\u0e33 &hellip; <a href=\"https:\/\/football-tribe.com\/thailand\/2018\/03\/28\/rajevac-thailand-team\/\" class=\"tribe-more-link\">Continue reading &#8220;\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19!\u0e23\u0e32\u0e40\u0e22\u0e27\u0e31\u0e0a\u0e0a\u0e35\u0e49\u0e0a\u0e31\u0e14\u0e0a\u0e49\u0e32\u0e07\u0e28\u0e36\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e15\u0e48\u0e40\u0e01\u0e21\u0e23\u0e31\u0e1a&#8221;<\/a><\/p>\n","protected":false},"author":68,"featured_media":23405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,69],"tags":[98,194],"class_list":["post-23404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thai-national-team","category-thai-football","tag-98","tag-194"],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/23404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/comments?post=23404"}],"version-history":[{"count":0,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/23404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media\/23405"}],"wp:attachment":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media?parent=23404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/categories?post=23404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/tags?post=23404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}