{"id":19308,"date":"2018-01-17T15:04:07","date_gmt":"2018-01-17T08:04:07","guid":{"rendered":"https:\/\/football-tribe.com\/thailand\/?p=19308"},"modified":"2018-01-17T15:06:12","modified_gmt":"2018-01-17T08:06:12","slug":"ratchaburi-new-season-2018","status":"publish","type":"post","link":"https:\/\/football-tribe.com\/thailand\/2018\/01\/17\/ratchaburi-new-season-2018\/","title":{"rendered":"\u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e21\u0e48! \u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07 3 \u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e38\u0e19\u0e1e\u0e25\u0e25\u0e38\u0e22\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 2018 27 \u0e21.\u0e04."},"content":{"rendered":"<p>\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u0e21\u0e34\u0e15\u0e23\u0e1c\u0e25 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07\u0e0a\u0e02\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e39\u0e49\u0e28\u0e36\u0e01\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2018 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e2a\u0e19\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1c\u0e25 \u0e2a\u0e40\u0e15\u0e40\u0e14\u0e35\u0e22\u0e21<\/p>\n<p>\u0e23\u0e32\u0e0a\u0e31\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e31\u0e27\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e35\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22 \u0e25\u0e07\u0e17\u0e33\u0e28\u0e36\u0e01\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e2a\u0e32\u0e21\u0e40\u0e2a\u0e49\u0e32\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 Boost Sporstfix Super Cup \u00a0\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e17\u0e35\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e39\u0e49\u0e28\u0e36\u0e01\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2018 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48 27 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e2a\u0e19\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1c\u0e25 \u0e2a\u0e40\u0e15\u0e40\u0e14\u0e35\u0e22\u0e21<\/p>\n<p>\u0e42\u0e14\u0e22 \u201c\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e1f\u0e25\u0e38\u0e04\u201d \u0e18\u0e19\u0e27\u0e31\u0e0a\u0e23 \u0e19\u0e34\u0e15\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32 \u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07 3 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e49\u0e21, \u0e21\u0e48\u0e27\u0e07(\u0e1e\u0e34\u0e40\u0e28\u0e29), \u0e14\u0e4d\u0e32(\u0e16\u0e48\u0e32\u0e19 charcoal) \u0e42\u0e14\u0e22\u0e2a\u0e35\u0e21\u0e48\u0e27\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e14\u0e33\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e08\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 399 \u0e15\u0e31\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e35\u0e2a\u0e49\u0e21 \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e2a\u0e35\u0e2a\u0e49\u0e21\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e43\u0e0a\u0e49\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 8 \u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e21\u0e32\u0e23\u0e27\u0e21\u0e44\u0e27\u0e49\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e01\u0e21\u0e2d\u0e38\u0e48\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21 \u0e0b\u0e39\u0e27\u0e2d\u0e19 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e17\u0e35\u0e21\u0e14\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e15\u0e49 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u0e21\u0e34\u0e15\u0e23\u0e1c\u0e25 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07\u0e0a\u0e02\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e39\u0e49\u0e28\u0e36\u0e01\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2018 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 &hellip; <a href=\"https:\/\/football-tribe.com\/thailand\/2018\/01\/17\/ratchaburi-new-season-2018\/\" class=\"tribe-more-link\">Continue reading &#8220;\u0e44\u0e2e\u0e44\u0e25\u0e15\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e21\u0e48! \u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e38\u0e14\u0e41\u0e02\u0e48\u0e07 3 \u0e2a\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e38\u0e19\u0e1e\u0e25\u0e25\u0e38\u0e22\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 2018 27 \u0e21.\u0e04.&#8221;<\/a><\/p>\n","protected":false},"author":11,"featured_media":18650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,77],"tags":[264],"class_list":["post-19308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thai-football","category-thai-league","tag-264"],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/19308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/comments?post=19308"}],"version-history":[{"count":0,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/posts\/19308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media\/18650"}],"wp:attachment":[{"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/media?parent=19308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/categories?post=19308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/football-tribe.com\/thailand\/wp-json\/wp\/v2\/tags?post=19308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}