{"id":5757,"date":"2017-06-06T14:16:04","date_gmt":"2017-06-06T09:46:04","guid":{"rendered":"https:\/\/football-tribe.com\/iran\/?p=5757"},"modified":"2017-06-06T17:22:52","modified_gmt":"2017-06-06T12:52:52","slug":"%d9%88%d8%a7%da%a9%d9%86%d8%b4-%d9%be%d8%b1%d8%b3%d9%be%d9%88%d9%84%db%8c%d8%b3%db%8c-%d9%87%d8%a7-%d8%a8%d9%87-%d9%82%d8%b1%d8%b9%d9%87-%d8%a7%d9%84%d8%a7%d9%87%d9%84%db%8c","status":"publish","type":"post","link":"https:\/\/football-tribe.com\/iran\/2017\/06\/06\/%d9%88%d8%a7%da%a9%d9%86%d8%b4-%d9%be%d8%b1%d8%b3%d9%be%d9%88%d9%84%db%8c%d8%b3%db%8c-%d9%87%d8%a7-%d8%a8%d9%87-%d9%82%d8%b1%d8%b9%d9%87-%d8%a7%d9%84%d8%a7%d9%87%d9%84%db%8c\/","title":{"rendered":"\u0648\u0627\u06a9\u0646\u0634 \u0628\u0631\u0627\u0646\u06a9\u0648 \u0648 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633\u06cc \u0647\u0627 \u0628\u0647 \u0642\u0631\u0639\u0647 \u0627\u0644\u0627\u0647\u0644\u06cc"},"content":{"rendered":"<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\">\u0641\u0648\u062a\u0628\u0627\u0644 \u062a\u0631\u0627\u06cc\u0628- \u0642\u0631\u0639\u0647 \u06a9\u0634\u06cc \u0645\u0631\u062d\u0644\u0647 \u06cc\u06a9 \u0686\u0647\u0627\u0631\u0645 \u0646\u0647\u0627\u06cc\u06cc \u0644\u06cc\u06af \u0642\u0647\u0631\u0645\u0627\u0646\u0627\u0646 \u0622\u0633\u06cc\u0627 \u0627\u0645\u0631\u0648\u0632 \u0628\u0631\u06af\u0632\u0627\u0631 \u0634\u062f \u0648 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0627\u0644\u0627\u0647\u0644\u06cc \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0631\u0648\u0628\u0631\u0648 \u0634\u0648\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u0647\u0631\u0686\u0646\u062f \u0627\u06cc\u0646 \u0642\u0631\u0639\u0647 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633\u06cc \u0647\u0627 \u0628\u0627\u06cc\u062f \u0647\u0631 \u062f\u0648 \u062f\u06cc\u062f\u0627\u0631 \u0631\u0641\u062a \u0648 \u0628\u0631\u06af\u0634\u062a \u0631\u0627 \u062f\u0631 \u0632\u0645\u06cc\u0646 \u0628\u06cc \u0637\u0631\u0641 \u0627\u0646\u062c\u0627\u0645 \u0628\u062f\u0647\u0646\u062f \u0627\u0645\u0627 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u0627\u06cc\u0646 \u0645\u0637\u0644\u0648\u0628 \u062a\u0631\u06cc\u0646 \u0642\u0631\u0639\u0647 \u0645\u0645\u06a9\u0646 \u0628\u0631\u0627\u06cc \u0642\u0631\u0645\u0632\u0647\u0627 \u0627\u0632 \u0646\u0638\u0631 \u0642\u062f\u0631\u062a \u062a\u06cc\u0645 \u062d\u0631\u06cc\u0641 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u0628\u0631\u0627\u0646\u06a9\u0648 \u0627\u06cc\u0648\u0627\u0646\u06a9\u0648\u0648\u06cc\u0686 \u0628\u0639\u062f \u0627\u0632 \u0627\u0639\u0644\u0627\u0645 \u0642\u0631\u0639\u0647 \u06af\u0641\u062a:&#8221; \u062a\u0642\u0631\u06cc\u0628\u0627 \u0647\u0645\u0647 \u062a\u06cc\u0645\u200c\u0647\u0627 \u06cc\u06a9\u0633\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u0647\u0645\u06af\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u06cc\u0644\u06cc \u062e\u0648\u0628\u06cc \u0627\u0632 \u062e\u0648\u062f\u0634\u0627\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646\u062f \u0648 \u0647\u06cc\u0686 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u0631\u0642\u0628\u0627\u06cc \u0645\u0627 \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u0627\u0644\u0627\u0647\u0644\u06cc \u0647\u0645 \u0645\u062b\u0644 \u0627\u0644\u0647\u0644\u0627\u0644\u060c \u062a\u06cc\u0645 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u062b\u0628\u0627\u062a \u0648 \u062e\u0648\u0628\u06cc \u0627\u0633\u062a \u0648 \u0635\u062f \u062f\u0631 \u0635\u062f \u0628\u0627\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0633\u062e\u062a\u06cc \u062f\u0631 \u0627\u0646\u062a\u0638\u0627\u0631 \u0645\u0627 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f\u060c \u0645\u062e\u0635\u0648\u0635\u0627 \u06a9\u0647 \u0628\u062f\u0648\u0646 \u062a\u0645\u0627\u0634\u0627\u06af\u0631 \u0628\u0627\u0632\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0645\u0633\u0627\u0644\u0647 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062e\u0648\u062f\u0645\u0627\u0646 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0622\u0645\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645 \u0686\u0648\u0646 \u062f\u0631 \u0641\u0635\u0644 \u062c\u062f\u06cc\u062f \u0647\u0645 \u062a\u06cc\u0645 \u0627\u0644\u0627\u0647\u0644\u06cc \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a \u0648 \u0642\u0637\u0639\u0627 \u0647\u062f\u0641 \u0645\u0627 \u0639\u0628\u0648\u0631 \u0627\u0632 \u0627\u06cc\u0646 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0628\u0647 \u0646\u06cc\u0645\u0647 \u0646\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u0648 \u06a9\u0627\u0645\u0644\u0627 \u0628\u0647 \u062e\u0648\u0627\u0633\u062a\u0647\u200c\u0645\u0627\u0646 \u0648 \u0647\u062f\u0641\u0645\u0627\u0646 \u0648 \u0641\u0634\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0648\u062c\u0648\u062f \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a\u060c \u0648\u0627\u0642\u0641 \u0647\u0633\u062a\u06cc\u0645 \u0648 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0644\u0647 \u0641\u0631\u0627\u0631 \u0646\u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.&#8221;<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u067e\u06cc\u0634\u06a9\u0633\u0648\u062a\u0627\u0646 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633 \u0647\u0645 \u0628\u0647 \u0627\u06cc\u0646 \u0642\u0631\u0639\u0647 \u0648\u0627\u06a9\u0646\u0634 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0642\u0631\u0639\u0647 \u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062a\u06cc\u0645 \u0628\u0631\u0627\u0646\u06a9\u0648 \u062a\u0648\u0635\u06cc\u0641 \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u062d\u0645\u06cc\u062f \u062f\u0631\u062e\u0634\u0627\u0646: &#8220;\u0628\u0647 \u0646\u0638\u0631\u0645 \u0642\u0631\u0639\u0647 \u062e\u0648\u0628\u06cc \u0627\u0633\u062a \u0648 \u067e\u06cc\u0634 \u0627\u0632 \u0627\u06cc\u0646 \u0647\u0645 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0645 \u0627\u0632 \u0628\u06cc\u0646 3 \u062a\u06cc\u0645 \u062d\u0627\u0636\u0631 \u0628\u0627 \u0627\u0644\u0627\u0647\u0644\u06cc \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0646\u06cc\u0645. \u0627\u06cc\u0646 \u062a\u06cc\u0645 \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0644\u0647\u0644\u0627\u0644 \u0648 \u0627\u0644\u0639\u06cc\u0646 \u062d\u0631\u06cc\u0641 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc \u0627\u0633\u062a \u0648 \u0634\u0627\u0646\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u067e\u06cc\u0631\u0648\u0632\u06cc \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u0641\u0631\u0635\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f \u0648 \u0628\u062a\u0648\u0627\u0646\u06cc\u0645 \u062f\u0631 \u062c\u0645\u0639 4 \u062a\u06cc\u0645 \u0646\u0647\u0627\u06cc\u06cc \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u06cc\u0645.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\">\u062e\u0648\u0628\u06cc \u0633\u06cc\u0633\u062a\u0645 \u062c\u062f\u06cc\u062f \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0628\u0627\u0632\u06cc\u200c\u0647\u0627 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0627 \u062a\u0627 \u0641\u06cc\u0646\u0627\u0644 \u0628\u0647 \u062a\u06cc\u0645\u200c\u0647\u0627\u06cc \u0634\u0631\u0642 \u0622\u0633\u06cc\u0627 \u0628\u0631\u062e\u0648\u0631\u062f \u0646\u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f \u0648 \u0641\u0642\u0637 \u062f\u0631 \u0641\u06cc\u0646\u0627\u0644 \u0631\u0648\u062f\u0631\u0631\u0648 \u062e\u0648\u0627\u0647\u06cc\u0645 \u0634\u062f. \u062a\u06cc\u0645\u200c\u0647\u0627\u06cc \u0634\u0631\u0642 \u0622\u0633\u06cc\u0627 \u0628\u0647 \u0645\u0631\u0627\u062a\u0628 \u062d\u0631\u06cc\u0641\u0627\u0646 \u062f\u0634\u0648\u0627\u0631\u062a\u0631\u06cc \u0647\u0633\u062a\u0646\u062f \u0648 \u0633\u0637\u062d \u0641\u0648\u062a\u0628\u0627\u0644 \u0622\u0646 \u0645\u0646\u0637\u0642\u0647 \u0628\u0627\u0644\u0627\u062a\u0631 \u0627\u0633\u062a.&#8221;<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\">\u0631\u0636\u0627 \u0634\u0627\u0647\u0631\u0648\u062f\u06cc:&#8221; \u0628\u0647 \u0646\u0638\u0631\u0645 \u0628\u0627 \u0642\u0631\u0639\u0647 \u062e\u0648\u0628\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u06cc\u0645. \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u0628\u0627\u0632\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0646\u0641\u0631\u0627\u062a \u062c\u062f\u06cc\u062f \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u062f \u0648 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0628\u0627 \u0631\u0627\u06cc\u0632\u0646\u06cc \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f \u062f\u0631 \u06a9\u0634\u0648\u0631\u06cc \u0645\u06cc\u0632\u0628\u0627\u0646 \u0627\u0644\u0627\u0647\u0644\u06cc \u0628\u0627\u0634\u06cc\u0645 \u06a9\u0647 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u0648\u0631\u0632\u0634\u06af\u0627\u0647 \u0628\u06cc\u0627\u06cc\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<span style=\"font-size: 12pt\"> \u0628\u0647 \u0646\u0638\u0631\u0645 \u0627\u0644\u0627\u0647\u0644\u06cc \u0642\u0648\u06cc \u062a\u0631 \u0627\u0632 \u0627\u0644\u0631\u06cc\u0627\u0646 \u0648 \u0644\u062e\u0648\u06cc\u0627 \u06a9\u0647 \u0628\u0627 \u0622\u0646\u0647\u0627 \u0628\u0627\u0632\u06cc \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645 \u0646\u06cc\u0633\u062a. \u0627\u0644\u0628\u062a\u0647 \u062a\u06cc\u0645 \u0627\u0644\u0627\u0647\u0644\u06cc \u0647\u0645 \u0628\u0627\u0632\u06cc\u06a9\u0646\u0627\u0646 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0647 \u062a\u06cc\u0645\u0634 \u0627\u0636\u0627\u0641\u0647 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f. \u062a\u0627 \u0632\u0645\u0627\u0646 \u0628\u0627\u0632\u06cc \u0647\u0645 \u0628\u0627\u0632\u06cc \u0647\u0627\u06cc \u062a\u062f\u0627\u0631\u06a9\u0627\u062a\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a \u0648 \u0628\u0631\u0627\u0646\u06a9\u0648 \u0627\u06cc\u0648\u0627\u0646\u06a9\u0648\u0648\u06cc\u0686 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u0622\u0646\u0627\u0644\u06cc\u0632 \u0628\u0627\u0632\u06cc \u0647\u0627\u06cc \u0622\u0646\u0647\u0627 \u0628\u0627 \u0622\u0645\u0627\u062f\u06af\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u0645\u0635\u0627\u0641 \u0627\u0644\u0627\u0647\u0644\u06cc \u0628\u0631\u0648\u062f.&#8221;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0641\u0648\u062a\u0628\u0627\u0644 \u062a\u0631\u0627\u06cc\u0628- \u0642\u0631\u0639\u0647 \u06a9\u0634\u06cc \u0645\u0631\u062d\u0644\u0647 \u06cc\u06a9 \u0686\u0647\u0627\u0631\u0645 \u0646\u0647\u0627\u06cc\u06cc \u0644\u06cc\u06af \u0642\u0647\u0631\u0645\u0627\u0646\u0627\u0646 \u0622\u0633\u06cc\u0627 \u0627\u0645\u0631\u0648\u0632 \u0628\u0631\u06af\u0632\u0627\u0631 \u0634\u062f \u0648 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0627\u0644\u0627\u0647\u0644\u06cc \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0631\u0648\u0628\u0631\u0648 \u0634\u0648\u062f. \u0647\u0631\u0686\u0646\u062f \u0627\u06cc\u0646 \u0642\u0631\u0639\u0647 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633\u06cc \u0647\u0627 \u0628\u0627\u06cc\u062f \u0647\u0631 \u062f\u0648 \u062f\u06cc\u062f\u0627\u0631 \u0631\u0641\u062a \u0648 \u0628\u0631\u06af\u0634\u062a \u0631\u0627 \u062f\u0631 \u0632\u0645\u06cc\u0646 \u0628\u06cc \u0637\u0631\u0641 \u0627\u0646\u062c\u0627\u0645 \u0628\u062f\u0647\u0646\u062f \u0627\u0645\u0627 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u0627\u06cc\u0646 \u0645\u0637\u0644\u0648\u0628 \u062a\u0631\u06cc\u0646 \u0642\u0631\u0639\u0647 \u0645\u0645\u06a9\u0646 \u0628\u0631\u0627\u06cc \u0642\u0631\u0645\u0632\u0647\u0627 \u0627\u0632 \u0646\u0638\u0631 \u0642\u062f\u0631\u062a \u062a\u06cc\u0645 \u062d\u0631\u06cc\u0641 \u0628\u0627\u0634\u062f. \u0628\u0631\u0627\u0646\u06a9\u0648 \u0627\u06cc\u0648\u0627\u0646\u06a9\u0648\u0648\u06cc\u0686 \u0628\u0639\u062f \u0627\u0632 \u0627\u0639\u0644\u0627\u0645 \u0642\u0631\u0639\u0647 \u06af\u0641\u062a:&#8221; \u062a\u0642\u0631\u06cc\u0628\u0627 \u0647\u0645\u0647 \u062a\u06cc\u0645\u200c\u0647\u0627 \u06cc\u06a9\u0633\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u0647\u0645\u06af\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u06cc\u0644\u06cc \u062e\u0648\u0628\u06cc \u0627\u0632 \u062e\u0648\u062f\u0634\u0627\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646\u062f \u0648 \u0647\u06cc\u0686 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u0631\u0642\u0628\u0627\u06cc \u0645\u0627 \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0627\u0644\u0627\u0647\u0644\u06cc \u0647\u0645 \u0645\u062b\u0644 \u0627\u0644\u0647\u0644\u0627\u0644\u060c \u062a\u06cc\u0645 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u062b\u0628\u0627\u062a \u0648 \u062e\u0648\u0628\u06cc \u0627\u0633\u062a \u0648 \u0635\u062f \u062f\u0631 \u0635\u062f &hellip; <a href=\"https:\/\/football-tribe.com\/iran\/2017\/06\/06\/%d9%88%d8%a7%da%a9%d9%86%d8%b4-%d9%be%d8%b1%d8%b3%d9%be%d9%88%d9%84%db%8c%d8%b3%db%8c-%d9%87%d8%a7-%d8%a8%d9%87-%d9%82%d8%b1%d8%b9%d9%87-%d8%a7%d9%84%d8%a7%d9%87%d9%84%db%8c\/\" class=\"tribe-more-link\">Continue reading &#8220;\u0648\u0627\u06a9\u0646\u0634 \u0628\u0631\u0627\u0646\u06a9\u0648 \u0648 \u067e\u0631\u0633\u067e\u0648\u0644\u06cc\u0633\u06cc \u0647\u0627 \u0628\u0647 \u0642\u0631\u0639\u0647 \u0627\u0644\u0627\u0647\u0644\u06cc&#8221;<\/a><\/p>\n","protected":false},"author":22,"featured_media":4734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[372,344],"class_list":["post-5757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-312","tag-372","tag-344"],"_links":{"self":[{"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/posts\/5757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/comments?post=5757"}],"version-history":[{"count":0,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/posts\/5757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/media\/4734"}],"wp:attachment":[{"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/media?parent=5757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/categories?post=5757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/football-tribe.com\/iran\/wp-json\/wp\/v2\/tags?post=5757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}