{"id":490,"count":2,"description":"","link":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/","name":"Stevan Jovetic","slug":"stevan-jovetic","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stevan Jovetic | Football Tribe Indonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stevan Jovetic | Football Tribe Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/\" \/>\n<meta property=\"og:site_name\" content=\"Football Tribe Indonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@footballtribeid\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/tag\\\/stevan-jovetic\\\/\",\"url\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/tag\\\/stevan-jovetic\\\/\",\"name\":\"Stevan Jovetic | Football Tribe Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/tag\\\/stevan-jovetic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/tag\\\/stevan-jovetic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stevan Jovetic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/#website\",\"url\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/\",\"name\":\"Football Tribe Indonesia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/football-tribe.com\\\/indonesia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stevan Jovetic | Football Tribe Indonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/","og_locale":"en_US","og_type":"article","og_title":"Stevan Jovetic | Football Tribe Indonesia","og_url":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/","og_site_name":"Football Tribe Indonesia","twitter_card":"summary_large_image","twitter_site":"@footballtribeid","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/","url":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/","name":"Stevan Jovetic | Football Tribe Indonesia","isPartOf":{"@id":"https:\/\/football-tribe.com\/indonesia\/#website"},"breadcrumb":{"@id":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/football-tribe.com\/indonesia\/tag\/stevan-jovetic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/football-tribe.com\/indonesia\/"},{"@type":"ListItem","position":2,"name":"Stevan Jovetic"}]},{"@type":"WebSite","@id":"https:\/\/football-tribe.com\/indonesia\/#website","url":"https:\/\/football-tribe.com\/indonesia\/","name":"Football Tribe Indonesia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/football-tribe.com\/indonesia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/football-tribe.com\/indonesia\/wp-json\/wp\/v2\/tags\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/football-tribe.com\/indonesia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/football-tribe.com\/indonesia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/football-tribe.com\/indonesia\/wp-json\/wp\/v2\/posts?tags=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}